{"id":17435,"date":"2020-05-22T08:33:51","date_gmt":"2020-05-22T06:33:51","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=17435"},"modified":"2020-05-22T08:33:51","modified_gmt":"2020-05-22T06:33:51","slug":"gassigehen-mit-hund-und-kind","status":"publish","type":"post","link":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/","title":{"rendered":"Gassigehen mit Hund und Kind"},"content":{"rendered":"<div id=\"pl-17435\" class=\"panel-layout\">\n<div id=\"pg-17435-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-17435-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-17435-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p>                            <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-featured-whatever wp-image-17499\" src=\"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-760x570.jpg\" alt=\"Gassigehen mit Hund und Kind\" width=\"760\" height=\"570\" srcset=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-760x570.jpg 760w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-700x525.jpg 700w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-233x175.jpg 233w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-175x131.jpg 175w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind-323x242.jpg 323w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/><div class=\"mobile-toc\"><\/div><\/p>\n<p>Du schlenderst ganz entspannt bei bestem Wetter mit dem Kinderwagen durch den Park und dein Vierbeiner trabt an durchh&auml;ngender Leine neben dem Kinderwagen her &ndash; was f&uuml;r eine sch&ouml;ne Vorstellung. Dieses Szenario muss und sollte aber kein blo&szlig;er Gedanke bleiben, schlie&szlig;lich k&ouml;nnte dir so eine ganze Menge Stress erspart bleiben. Wir geben dir hier Tipps f&uuml;r das erfolgreiche Gassigehen mit Hund und Kind.<\/p>\n<h2 id=\"leinenfhrigkeit\">Leinenf&uuml;hrigkeit<\/h2>\n<p>Du hast es schon erahnen k&ouml;nnen: Die <a href=\"\/magazin\/hunde\/erziehung\/leinenfuehrigkeit\/\" target=\"_blank\" rel=\"noopener noreferrer\">Leinenf&uuml;hrigkeit<\/a> spielt eine zentrale Rolle bei <strong>entspannten Spazierg&auml;ngen<\/strong>, ob mit oder ohne Kinderwagen. Damit der Hund wei&szlig;, wie er korrekt laufen soll, muss er das zun&auml;chst auch gelernt haben. Falls die Leinenf&uuml;hrigkeit noch nicht klappt, beginne das Training ganz in Ruhe, erst im Haus ohne Ablenkung, sp&auml;ter im Garten und dann erst auf der Stra&szlig;e. Vielleicht vereinbarst du auch ein paar Trainingsstunden mit einem professionellen <a href=\"\/magazin\/zoo-experten\/gastautoren-experten\/hundetraining-perdita-luebbe-im-zooroyal-live-interview\/\">Hundetrainer<\/a>, der dir bei dem Training mit langj&auml;hriger Erfahrung zur Seite stehen kann und dich anleitet.<\/p>\n<p>Wei&szlig; dein Hund schlie&szlig;lich, was du dir von ihm w&uuml;nschst, kannst du den Kinderwagen (am besten zun&auml;chst ohne Kind) in dein Training miteinbeziehen.<\/p>\n<h2 id=\"hund-und-kinderwagen\">Hund und Kinderwagen<\/h2>\n<p>Damit eine entspannte Atmosph&auml;re bei dem t&auml;glichen Spaziergang herrscht, darf dein Hund keine <strong>Angst<\/strong> vor dem Kinderwagen haben. Sollte das der Fall sein, ist es wichtig, dass du noch ein paar Schritte zur&uuml;ckgehst und mit der <strong>positiven Verkn&uuml;pfung<\/strong> des Kinderwagens anf&auml;ngst. Dieser soll f&uuml;r den Hund etwas Tolles sein, schlie&szlig;lich ist er auch meistens der Grund, weshalb es nach drau&szlig;en ins Gr&uuml;ne geht! &Uuml;berfordere deinen Vierbeiner nicht, indem du verlangst, dass er sehr dicht nebenher l&auml;uft. Gruselt er sich noch vor dem Gef&auml;hrt, ist es auch v&ouml;llig in Ordnung, wenn er etwas mehr Abstand h&auml;lt, solange er nicht beginnt zu ziehen oder stark abgelenkt zu sein.<\/p>\n<p>L&auml;uft dein Hund bei normalen Spazierg&auml;ngen an deiner linken Seite, so sollte er dort auch laufen, wenn du den Kinderwagen dabei schiebst. Achte darauf, dass du aufmerksam bist und <strong>richtiges Verhalten lobst<\/strong>. Halte die Trainingseinheiten so kurz, dass es am besten gar nicht erst zu Fehlverhalten, das du korrigieren m&uuml;sstest, kommen kann. Denk dran: dein Hund lernt am Erfolg! Deshalb w&auml;re es super, wenn gerade am Anfang vielleicht dein Mann, deine Eltern oder Schwiegereltern auf dein Kind aufpassen w&uuml;rden, damit du mit dem gemeinsamen Spaziergang nicht gleich ins kalte Wasser geschmissen wirst. So kannst du erst einmal getrennt gehen und deinem Kind und auch deinem Hund jeweils deine <strong>ungeteilte Aufmerksamkeit<\/strong> schenken, wenn du mit ihnen unterwegs bist.<\/p>\n<p><strong>Wichtig:<\/strong> Egal, wie gut dein Hund sp&auml;ter leinenf&uuml;hrig l&auml;uft, <strong>befestige die Leine niemals direkt am Kinderwagen<\/strong>. Es kann immer zu unvorhergesehenen Ereignissen kommen. Dein Hund k&ouml;nnte sich erschrecken, in die Leine springen und den Kinderwagen dabei mitrei&szlig;en. Behalte die Leine also immer in der Hand, um solche <strong>Unf&auml;lle zu vermeiden<\/strong>.<\/p>\n<h2 id=\"wo-bleibt-denn-da-die-entspannung\">Wo bleibt denn da die Entspannung?<\/h2>\n<p>Eine gute Vorbereitung ist das halbe Leben! Nach einem konsequenten Training w&auml;re der Vierbeiner nun also startklar. Fehlen nur noch dein Kind und eine gute Ordnung. &Uuml;berlege dir vorab, was du alles w&auml;hrend des Spaziergangs ben&ouml;tigst und wo du diese Dinge hinsteckst, um sie in k&uuml;rzester Zeit <strong>griffbereit<\/strong> zu haben. Plane ruhig eine l&auml;ngere Runde, damit du <strong>Pausen<\/strong> machen kannst, die <strong>Entspannung<\/strong> bringen. Es ist sinnvoll die Route so zu w&auml;hlen, dass dein Hund an einem geeigneten Platz auch ausgiebig toben und angestaute Energie ablassen darf. Schlie&szlig;lich sollte der Gassi-Gang auch f&uuml;r ihn nicht nur Training bedeuten, sondern auch <strong>Spiel und Spa&szlig;<\/strong> sein. Neben dem braven an der Leine laufen braucht dein Hund an geeigneter Stelle auch den Ausgleich, um richtig Hund sein zu d&uuml;rfen. Je nachdem, wie es dir dein Kind erm&ouml;glicht, kannst du auch das <a href=\"\/hund\/hundespielzeug\/\" target=\"_blank\" rel=\"noopener noreferrer\">Lieblingsspielzeug<\/a> deines Vierbeiners werfen oder verstecken, um es ihn anschlie&szlig;end wiederbringen zu lassen. Ausgelastet wird es deinem Hund viel leichter fallen, entspannt neben dem Kinderwagen weiterzugehen.<\/p>\n<p>Zwischendurch kannst du auch ruhig einmal eine Parkbank ansteuern, um dort eine Pause zu machen. Lasse deinen Hund abliegen und wenn es dich mehr beruhigt, binde das Leinenende an die Bank. So kannst du dich in aller Ruhe um dein Kind k&uuml;mmern oder die Ruhe genie&szlig;en. Hat dein Vierbeiner noch Probleme mit dem Warten bzw. der Entspannung, kannst du f&uuml;r den Fall einer solchen Pause einen <a href=\"\/hund\/hundefutter\/hundesnacks\/kauknochen?src=category&amp;el=teaser-box\" target=\"_blank\" rel=\"noopener noreferrer\">Kausnack<\/a> einpacken, den er bekommt. Das Kauen wird ihm helfen <strong>herunterzufahren<\/strong> und verkn&uuml;pft die Pause gleich mit etwas Positivem.<\/p>\n<p>Es wird zwar einige Zeit dauern, bis sich ein eingespielter Ablauf entwickelt, der f&uuml;r alle am besten passt. Aber ist es dann soweit, ist es doch etwas ganz besonders Sch&ouml;nes, mit Hund und Kind wie in der Wunschvorstellung stressfrei zusammen unterwegs zu sein!<\/p>\n<hr>\n<p><strong><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-12717 alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg\" alt=\"Kristina\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-300x221.jpg 300w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-768x566.jpg 768w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-760x560.jpg 760w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-323x238.jpg 323w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-380x280.jpg 380w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1.jpg 905w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>Kristina Ziemer-Falke<\/strong> ist zertifizierte Hundetrainerin und Verhaltensberaterin durch die Tier&auml;rztekammer Schleswig-Holstein und das Messerli Forschungsinstitut der Veterin&auml;rmedizinischen Universit&auml;t Wien. Dar&uuml;ber hinaus verf&uuml;gt sie &uuml;ber viele Zusatzausbildungen und Schwerpunkte und ist im Pr&uuml;fungsausschuss der Tier&auml;rztekammer Niedersachsen f&uuml;r die Hundetrainerzertifizierungen.<br \/>\nMit ihrem Mann J&ouml;rg Ziemer gr&uuml;ndete sie das Schulungszentrum <a href=\"https:\/\/www.ziemer-falke.de\/\" target=\"_blank\" rel=\"nofollow noopener noreferrer\">Ziemer &amp; Falke<\/a>, in dem sie seit vielen Jahren mit viel Herz, Leidenschaft und Kompetenz Hundetrainer in ganz Deutschland ausbilden und viele Weiterbildungsangebote anbieten. Viele kennen Kristina au&szlig;erdem als erfolgreiche Autorin von Fachb&uuml;chern f&uuml;r Hundetrainer und Hundehalter sowie aus Artikeln beliebter Hundezeitschriften.<\/p>\n<hr><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/p><\/div>\n<div id=\"pg-17435-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-17435-1-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-17435-1-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/dokas-huehnermaegen-gefriergetrocknet-3x20g\/1000078861\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jh2ppe-SA-X-KPx.jpg?host=ct\"\n                alt=\"Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Dokas                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    5.99 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        99.83 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/dokas-huehnermaegen-gefriergetrocknet-3x20g\/1000078861\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/beeztees-dschungel-zebraschwanz-50x6-cm\/1000108984\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"Beeztees Dschungel Zebraschwanz 50x6 cm\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/c24bt3-evyuO5vr.jpg?host=ct\"\n                alt=\"Beeztees Dschungel Zebraschwanz 50x6 cm\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Beeztees                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Beeztees Dschungel Zebraschwanz 50x6 cm<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    6.39 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/beeztees-dschungel-zebraschwanz-50x6-cm\/1000108984\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/adventuros-training-lachs-6x115g\/1000105444\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"AdVENTuROS Training Lachs 6x115g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/sixf75-XP5K5gwB.jpg?host=ct\"\n                alt=\"AdVENTuROS Training Lachs 6x115g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    AdVENTuROS                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">AdVENTuROS Training Lachs 6x115g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    13.49 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        19.55 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/adventuros-training-lachs-6x115g\/1000105444\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a0495f1e7234\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/dokas-huehnermaegen-gefriergetrocknet-3x20g\/1000078861\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/jh2ppe-SA-X-KPx.jpg?host=ct\"\n                                    alt=\"Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g\">\n\n                            <div id=\"swiper-button-next6a0495f1e7234\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a0495f1e7234\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Dokas                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Dokas H\u00fchnerm\u00e4gen, gefriergetrocknet 3x20g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                5.99 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    99.83 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/dokas-huehnermaegen-gefriergetrocknet-3x20g\/1000078861\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/beeztees-dschungel-zebraschwanz-50x6-cm\/1000108984\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"Beeztees Dschungel Zebraschwanz 50x6 cm\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/c24bt3-evyuO5vr.jpg?host=ct\"\n                                    alt=\"Beeztees Dschungel Zebraschwanz 50x6 cm\">\n\n                            <div id=\"swiper-button-next6a0495f1e7234\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a0495f1e7234\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Beeztees                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Beeztees Dschungel Zebraschwanz 50x6 cm<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                6.39 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/beeztees-dschungel-zebraschwanz-50x6-cm\/1000108984\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/adventuros-training-lachs-6x115g\/1000105444\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" class=\"article__wrapper--productimage\" title=\"AdVENTuROS Training Lachs 6x115g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/sixf75-XP5K5gwB.jpg?host=ct\"\n                                    alt=\"AdVENTuROS Training Lachs 6x115g\">\n\n                            <div id=\"swiper-button-next6a0495f1e7234\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a0495f1e7234\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                AdVENTuROS                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">AdVENTuROS Training Lachs 6x115g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                13.49 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    19.55 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/adventuros-training-lachs-6x115g\/1000105444\/?icid=magproteaser_hunde_gassigehen-mit-hund-und-kind_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a0495f1e7234\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a0495f1e7234\",\n                prevEl: \"#swiper-button-prev6a0495f1e7234\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Du schlenderst ganz entspannt bei bestem Wetter mit dem Kinderwagen durch den Park und dein Vierbeiner trabt an durchh&auml;ngender Leine neben dem Kinderwagen her &ndash; was f&uuml;r eine sch&ouml;ne Vorstellung&#8230;. <a class=\"moretag\" href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":45,"featured_media":17499,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,5],"tags":[2692,2693,2694,2691],"class_list":["post-17435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-erziehung","category-hunde","tag-gassi-mit-hund-und-kind","tag-hund-und-kind","tag-hund-und-kinderwagen","tag-spazieren-mit-hund-und-kind"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gassigehen mit Hund und Kind | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gassigehen mit Hund und Kind\" \/>\n<meta property=\"og:description\" content=\"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-22T06:33:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"5472\" \/>\n\t<meta property=\"og:image:height\" content=\"3648\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Kristina Ziemer-Falke\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kristina Ziemer-Falke\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/\"},\"author\":{\"name\":\"Kristina Ziemer-Falke\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\"},\"headline\":\"Gassigehen mit Hund und Kind\",\"datePublished\":\"2020-05-22T06:33:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/\"},\"wordCount\":1004,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gassi-mit-hund-und-kind.jpg\",\"keywords\":[\"gassi mit hund und kind\",\"hund und kind\",\"hund und kinderwagen\",\"spazieren mit hund und kind\"],\"articleSection\":[\"Erziehung\",\"Hunde Magazin\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/\",\"name\":\"Gassigehen mit Hund und Kind | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gassi-mit-hund-und-kind.jpg\",\"datePublished\":\"2020-05-22T06:33:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\"},\"description\":\"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gassi-mit-hund-und-kind.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/08\\\/gassi-mit-hund-und-kind.jpg\",\"width\":5472,\"height\":3648,\"caption\":\"Gassigehen mit Hund und Kind\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/gassigehen-mit-hund-und-kind\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gassigehen mit Hund und Kind\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/278fd41e5e1019ad63bd3faa61c71d98\",\"name\":\"Kristina Ziemer-Falke\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/04\\\/Kristina_Ziemer_Falke-1-96x96.jpg\",\"caption\":\"Kristina Ziemer-Falke\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gassigehen mit Hund und Kind | ZooRoyal Magazin","description":"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/","og_locale":"de_DE","og_type":"article","og_title":"Gassigehen mit Hund und Kind","og_description":"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2020-05-22T06:33:51+00:00","og_image":[{"width":5472,"height":3648,"url":"https:\/\/www.zooroyal.at\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg","type":"image\/jpeg"}],"author":"Kristina Ziemer-Falke","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"Kristina Ziemer-Falke","Est. reading time":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/"},"author":{"name":"Kristina Ziemer-Falke","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98"},"headline":"Gassigehen mit Hund und Kind","datePublished":"2020-05-22T06:33:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/"},"wordCount":1004,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg","keywords":["gassi mit hund und kind","hund und kind","hund und kinderwagen","spazieren mit hund und kind"],"articleSection":["Erziehung","Hunde Magazin"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/","name":"Gassigehen mit Hund und Kind | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg","datePublished":"2020-05-22T06:33:51+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98"},"description":"Am Anfang kann das Gassigehen mit Hund und Kind noch schwierig sein. Lies hier, wie dein Hund auch mit dem Kinderwagen entspannt umgeht.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#primaryimage","url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg","contentUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2019\/08\/gassi-mit-hund-und-kind.jpg","width":5472,"height":3648,"caption":"Gassigehen mit Hund und Kind"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/gassigehen-mit-hund-und-kind\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Gassigehen mit Hund und Kind"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/278fd41e5e1019ad63bd3faa61c71d98","name":"Kristina Ziemer-Falke","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","contentUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/04\/Kristina_Ziemer_Falke-1-96x96.jpg","caption":"Kristina Ziemer-Falke"}}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/17435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/comments?post=17435"}],"version-history":[{"count":5,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/17435\/revisions"}],"predecessor-version":[{"id":20431,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/17435\/revisions\/20431"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/media\/17499"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/media?parent=17435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/categories?post=17435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/tags?post=17435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}