{"id":12585,"date":"2018-04-18T15:09:49","date_gmt":"2018-04-18T13:09:49","guid":{"rendered":"https:\/\/www.zooroyal.de\/magazin\/?p=12585"},"modified":"2024-07-03T14:42:34","modified_gmt":"2024-07-03T12:42:34","slug":"loewchen","status":"publish","type":"post","link":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/loewchen\/","title":{"rendered":"L\u00f6wchen"},"content":{"rendered":"<div id=\"pl-12585\" class=\"panel-layout\">\n<div id=\"pg-12585-0\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-12585-0-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"panel-12585-0-0-0\" class=\"so-panel widget widget_sow-editor panel-first-child panel-last-child\" data-index=\"0\">\n<div class=\"so-widget-sow-editor so-widget-sow-editor-base\">\n<div class=\"siteorigin-widget-tinymce textwidget\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-12589 size-full\" title=\"L&ouml;wchen\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg\" alt=\"L&ouml;wchen\" width=\"760\" height=\"560\" srcset=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg 760w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560-300x221.jpg 300w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560-323x238.jpg 323w, https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560-380x280.jpg 380w\" sizes=\"auto, (max-width: 760px) 100vw, 760px\" \/>\n<style>\n    .characterGrid {\n        display: grid;\n        grid-template-columns: auto auto auto auto;\n    }\n\n    .characterGrid div {\n        padding: 0.25em;\n    }\n<\/style>\n\n<div class=\"characteristics\">\n    <div class=\"header\">\n        <h2>L\u00f6wchen Steckbrief<\/h2>\n        <div class=\"badge\">\n            <i class=\"halflings halflings-ok\"><\/i>         <\/div>\n    <\/div>\n\n    <div width=\"100%\" class=\"characterGrid\">\n\t\t            <div><strong>Name<\/strong><\/div>\n            <div>L\u00f6wchen Steckbrief<\/div>\n\t\t            <div><strong>Herkunft<\/strong><\/div>\n            <div>Frankreich<\/div>\n\t\t            <div><strong>Lebenserwartung<\/strong><\/div>\n            <div>15 Jahre<\/div>\n\t\t            <div><strong>FCI-Standard<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/fci-gruppen\/fci-gruppe-9\/\">Gruppe 9: Gesellschafts- und Begleithunde<\/a><\/div>\n\t\t            <div><strong>Funktion<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/familienhunde\/\">Familienhund<\/a><\/div>\n\t\t            <div><strong>Gr\u00f6\u00dfe<\/strong><\/div>\n            <div><a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/mini-hunderassen\/\">Mini Hunderassen<\/a><\/div>\n\t\t            <div><strong>Gewicht<\/strong><\/div>\n            <div>ca. 6 kg<\/div>\n\t\t            <div><strong>H\u00e4ufige Krankheiten<\/strong><\/div>\n            <div>Augenreizung, besch\u00e4digte Tr\u00e4nenkan\u00e4le<\/div>\n\t\t            <div><strong>Felll\u00e4nge<\/strong><\/div>\n            <div>lang, seidig, gewellt<\/div>\n\t\t            <div><strong>Charakter\/Wesen<\/strong><\/div>\n            <div>Ein freundlicher Begleiter, ideal f\u00fcr die heutige Zeit<\/div>\n\t\t            <div><strong>Fellfarbe<\/strong><\/div>\n            <div>alle Farben<\/div>\n\t\t    <\/div>\n\n            <div><strong>Besonderheiten<\/strong><\/div>\n        <div><p>Stadthund<br \/>\nAnf\u00e4ngerhund<br \/>\nAlte Hunderasse<\/p>\n<\/div>\n    <\/div>\n<!-- \/characteristics --><div class=\"mobile-toc\"><\/div>\n<\/p>\n<h2 id=\"rassenmerkmale-und-erscheinungsbild\"><span style=\"font-weight: 400;\">Rassenmerkmale und Erscheinungsbild<\/span><\/h2>\n<h3 id=\"wie-sieht-ein-lwchen-aus\">Wie sieht ein L&ouml;wchen aus?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen, im Original &#8222;Petit Chien Lion&#8220;, ist eher <strong>kleiner Hund<\/strong> mit langem, seidigem Fell. Das L&ouml;wchen hat ein quadratisches Geb&auml;ude, das durchaus <strong>robust<\/strong> ist. Es hat eine Widerristh&ouml;he zwischen <strong>20 und 35 Zentimetern.<\/strong> Das ist eine recht breite Spanne. So k&ouml;nnen als Gewicht nur etwa 6 Kilogramm als Anhaltspunkt gegeben werden. Zum Haarkleid legt der Standard fest:<\/span><span style=\"font-weight: 400;\"> &#8222;Seidig, lang, gewellt, dicht; ohne Unterwolle.&#8220; <strong>Als Farben<\/strong> sind alle erlaubt, ausdr&uuml;cklich auch kombinierten F&auml;rbungen. Die Rute wird &uuml;ber dem R&uuml;cken getragen. Der ganze Hund macht einen fr&ouml;hlichen, aufgeweckten Eindruck und so ist er auch. Der Standard schreibt ferner:<\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\"> &#8222;Er ist ein kleiner Hund. Intelligent, voller Elan und mit lebhaftem Ausdruck wirkt er sehr aufgeweckt; insgesamt robust mit gutem Knochenbau, einem kurzen und gut proportionierten K&ouml;rper, mit windhundartiger Silhouette und hochgetragenem Kopf.&#8220; <\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">F&uuml;r Hundeausstellungen wird die <strong>L&ouml;wenschur<\/strong> verlangt. Dazu hei&szlig;t es im Standard: &#8222;Der stolze und forsche Gang, seine flatternde M&auml;hne, wird durch die l&ouml;wenartige Schur noch betont; die nicht rasierten Teile m&uuml;ssen v&ouml;llig <strong>nat&uuml;rlich bleiben<\/strong>, in keinem Fall sollten sie geschnitten sein.&#8220; <\/span><\/p>\n<h3 id=\"wie-alt-wird-ein-lwchen\">Wie alt wird ein L&ouml;wchen?<\/h3>\n<p><span style=\"font-weight: 400;\">Ein seri&ouml;s gez&uuml;chtetes L&ouml;wchen hat eine Lebenserwartung von <strong>15 Jahren.<\/strong><\/span><\/p>\n<h2 id=\"wesenszge-und-charaktereigenschaften\"><span style=\"font-weight: 400;\">Wesensz&uuml;ge und Charaktereigenschaften<\/span><\/h2>\n<h3 id=\"welche-eigenschaften-hat-ein-lwchen\">Welche Eigenschaften hat ein L&ouml;wchen?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen ist ein <strong>gelernter Begleiter des Menschen.<\/strong> Anders als beispielsweise die kleinen Terriern, die erst in j&uuml;ngerer Vergangenheit von ausgemachten Arbeitshunden zu Begleitern umgeschult wurden, kennt der L&ouml;wchen die <strong>Aufgaben als Gesellschafts- und Begleithund<\/strong> bereits seit tausenden Jahren. Sein Wesen kennzeichnet der Standard als: <\/span><\/p>\n<blockquote>\n<p><span style=\"font-weight: 400;\">&#8222;Sehr schmusig und folgsam gegen&uuml;ber seinem Herren, aber aufmerksam und aufnahmef&auml;hig, locker in allen Situationen, kann er nach Bedarf ruhig und diskret bleiben. Sein ehrlicher und z&auml;rtlicher Blick versucht alles zu verstehen was man von ihm erwartet.&#8220; <\/span><\/p>\n<\/blockquote>\n<p><span style=\"font-weight: 400;\">Der kleine Hund hat aber durchaus <strong>seinen eigenen Willen.<\/strong> Trotzdem zeigt er kaum Ecken und Kanten, die seine Passion, seiner Familie Freude zu bereiten, entgegenstehen k&ouml;nnten. Er will f&uuml;r und mit seinen Menschen leben. Der putzige Hund ist ein <strong>cleveres, neugieriges und intelligentes Kerlchen,<\/strong> das immer wieder &uuml;berrascht und uns zum Schmunzeln bringt. Auch sollte man die <strong>Geschicklichkeit<\/strong> dieser Hunde nicht untersch&auml;tzen. Viele Berichte besagen, dass man dem L&ouml;wchen gut kleine Kunstst&uuml;cke beibringen kann. Trotzdem ist er nicht &uuml;beraktiv oder gar nerv&ouml;s. L&ouml;wchen sind von einem fr&ouml;hlichen Wesen und immer wieder gerne zu einem Spiel aufgelegt- kurz ideale Begleiter, die uns viel Freude bereiten. Das L&ouml;wchen ist auch<strong> f&uuml;r Anf&auml;nger<\/strong> gut geeignet.&nbsp;<\/span><\/p>\n<h2 id=\"herkunft-geschichte\"><span style=\"font-weight: 400;\">Herkunft &amp; Geschichte<\/span><\/h2>\n<h3 id=\"woher-kommt-das-lwchen\">Woher kommt das L&ouml;wchen?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen entstammt einer uralten<strong> Familie von <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/schosshunde\/\">Scho&szlig;<\/a>&#8211; und Begleithunden,<\/strong> die unter dem Namen Bichons zusammengefasst werden. Es stammt aus <strong>Frankreich und Belgien<\/strong>. Auf Franz&ouml;sisch wird es &#8222;Bichon petit chien-lion&#8220; oder &#8222;Petit Chien Lion&#8220; genannt. Die Wurzeln der Bichons lassen sich, wie sonst selten bei Hunderassen so deutlich, bis in die <strong>Antike<\/strong> nachverfolgen. In den Hafenst&auml;dten des Mittelmeers waren Bichons die gesch&auml;tzten Begleiter der Damen aus besserem Hause. Sie galten als wertvolle Geschenke. Schon Aristoteles beschrieb vor 2.400 Jahren einen &#8222;melit&auml;ischen Hund, der von auff&auml;llig kleinem Wuchs sei&#8220;. Zahlreiche weitere Schriften, Kunstwerke wie ein Vasengem&auml;lde aus dem Jahr 100 vuZ oder Plastiken aus Stein belegen die Existenz und hohe Wertsch&auml;tzung dieser Kleinhunde seit Menschengedenken. Die Menschen hatten offensichtlich schon sehr fr&uuml;h und in den verschiedensten Kulturen das Bed&uuml;rfnis nach einem Hund als Begleiter, als Partner der Psyche. Der L&ouml;wchen ist eng mit dem <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/malteser\/\">Malteser<\/a>,<a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/havaneser\/\"> Havaneser<\/a> und dem <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/bologneser\/\">Bologneser<\/a> verwandt. In einem der &auml;ltesten B&uuml;cher &uuml;ber Hunde nach der Antike, 1550 von Conrad Gesner geschrieben, werden diese Hunde eindeutig beschrieben &#8211; nicht zu verwechseln etwa mit einem <strong>Kleinpudel.<\/strong> In einer Illustration dazu, 1669 angefertigt, wird ein L&ouml;wchen in seiner auch heute noch typischen Schur gezeigt. Als Scho&szlig;hunde der reichen Damen kamen die Bichons um die ganze Welt. Bichons wie das L&ouml;wchen sind der lebende Beweis daf&uuml;r, dass man auch Begleithunde &uuml;ber Jahrhunderte hinweg<strong> gesund z&uuml;chten<\/strong> kann. Gerade in unserer heutigen oft hektischen Zeit sind Hunde wie das L&ouml;wchen eine gute Wahl. Denn eines sind sie sicher: angenehme und intelligente <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/familienhund\/\"><strong>Familienhunde<\/strong><\/a>, die sich auch in der Etagenwohnung einer Gro&szlig;stadt richtig wohl f&uuml;hlen und auch damit zufrieden geben. Von manchen Hundefreunden werden Scho&szlig;hunde wie die Bichons gerne bel&auml;chelt und zuweilen gar als &#8222;Fehlentwicklung&#8220; unserer heutigen Gesellschaft gesehen. Doch weit gefehlt. Sie haben eine &auml;u&szlig;erst wichtige Funktion und einen hohen Nutzen; denn solche Hunde tun schlicht unserer Psyche gut. 1961 erfolgte die offizielle Anerkennung dieser historischen Rasse durch die F&eacute;d&eacute;ration Cynologique Internationale. In Deutschland fallen<strong> 100 und 150 Welpen pro Jahr<\/strong> unter dem Dach des VDHs.<\/span><\/p>\n<h2 id=\"beliebte-mixe\">Beliebte Mixe<\/h2>\n<p><span style=\"font-weight: 400;\">Mixe mit L&ouml;wchen sind selten und wenn, dann unproblematisch.<\/span><\/p>\n<h2 id=\"pflege-gesundheit-und-krankheiten\"><span style=\"font-weight: 400;\">Pflege, Gesundheit und Krankheiten<\/span><\/h2>\n<h3 id=\"wie-viel-pflege-braucht-ein-lwchen\">Wie viel Pflege braucht ein L&ouml;wchen?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen haart nicht. Du solltest es aber <strong>zwei- bis dreimal pro Woche k&auml;mmen<\/strong>. Au&szlig;erdem ist es wichtig, die Augen und den Po frei zu scheren sowie regelm&auml;&szlig;ig die Haare an den F&uuml;&szlig;en oder in den Ohren zu entfernen.<\/span><\/p>\n<h3 id=\"gibt-es-rassetypische-krankheiten\">Gibt es rassetypische Krankheiten?<\/h3>\n<p><span style=\"font-weight: 400;\"> Das L&ouml;wchen ist eine<strong> gesunde Hunderasse.<\/strong> Ein allzu &uuml;ppiges Fell kann jedoch die Augen reizen und so Irritationen hervorrufen. Zuweilen sind &uuml;berdies die <strong>Tr&auml;nenkan&auml;le gesch&auml;digt,<\/strong> so dass st&auml;ndig Augenfl&uuml;ssigkeit aus dem Auge flie&szlig;t. Das verklebt diesen Bereich und ist als r&ouml;tliche F&auml;rbung auf hellem Fell nicht zu &uuml;bersehen. Hierauf solltest du schon vor dem Kauf achten (Elterntiere).&nbsp; Das Hauptproblem f&uuml;r die Gesundheit des L&ouml;wchens sind jedoch die vielen <strong>unseri&ouml;sen Anbieter<\/strong> von Welpen im Internet.<\/span><\/p>\n<h2 id=\"wissenswertes-ber-die-ernhrung-des-lwchen\"><span style=\"font-weight: 400;\">Wissenswertes &uuml;ber die Ern&auml;hrung des L&ouml;wchen<\/span><\/h2>\n<h3 id=\"welches-futter-ist-fr-ein-lwchen-am-besten\">Welches Futter ist f&uuml;r ein L&ouml;wchen am besten?<\/h3>\n<p><span style=\"font-weight: 400;\">Der L&ouml;wchen stellt keine besonderen Anspr&uuml;che an seine Ern&auml;hrung. Nat&uuml;rlich ist hochwertiges Futter gut f&uuml;r seine Gesundheit und er schmeckt es auch. Auch dieser kleine Hund mag einen <strong>fleischigen Rinderknochen<\/strong> und <strong>frisches Fleisch.<\/strong> Der L&ouml;wchen eignet sich sogar zum <a href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/was-ist-barf\/\">Barfen.<\/a><\/span><\/p>\n<h2 id=\"aktivitten-mit-dem-lwchen\"><span style=\"font-weight: 400;\">Aktivit&auml;ten mit dem L&ouml;wchen<\/span><\/h2>\n<h3 id=\"wie-viel-bewegung-braucht-ein-lwchen\">Wie viel Bewegung braucht ein L&ouml;wchen?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen braucht keine t&auml;gliche Arbeit oder intensive Besch&auml;ftigung wie Agility, um sich bei seinen Menschen wohl zu f&uuml;hlen.&nbsp;<\/span><\/p>\n<h2 id=\"berlegungen-vor-der-anschaffung\"><span style=\"font-weight: 400;\">&Uuml;berlegungen vor der Anschaffung<\/span><\/h2>\n<h3 id=\"was-muss-ich-bei-der-anschaffung-beachten\">Was muss ich bei der Anschaffung beachten?<\/h3>\n<p><span style=\"font-weight: 400;\">Willst Du dein Leben mit einem L&ouml;wchen teilen, solltest Du dich lange vor der Anschaffung nach einem <strong>Z&uuml;chter<\/strong> umschauen und hier Kontakte kn&uuml;pfen. Der Z&uuml;chter sollte dem <strong>VDH<\/strong> angeschlossen sein und seine Hunde auf die besonderen Risiken hinsichtlich Erbkrankheiten getestet haben. Das ist in der seri&ouml;sen Zucht selbstverst&auml;ndlich. Zudem sollte <strong>keine Inzucht<\/strong> vorliegen, was Du anhand des Stammbaums absch&auml;tzen kannst, wenn dort kein Name doppelt auftaucht. Der Z&uuml;chter sollte seinen Wurf per Foto gut dokumentiert haben. Du solltest Dir den Wurf zusammen mit der Mutterh&uuml;ndin, nach Absprache, vor Ort anschauen k&ouml;nnen. Bitte kaufe keinen L&ouml;wchen &uuml;bers Internet, da dort gerade bei solche kleineren Begleithunderassen das Risiko sehr gro&szlig; ist, dass der Welpe von einem &#8211; in aller Regel gut getarntem &#8211; Hundeh&auml;ndler, Vermehrer und aus einer Puppy Mill kommt. Das ist deine Verantwortung in Sachen Tierschutz und zudem erspart es dir und deinem Hund mit hoher Wahrscheinlichkeit viele G&auml;nge zum Tierarzt.<\/span><\/p>\n<h2 id=\"erziehung-und-haltung\"><span style=\"font-weight: 400;\">Erziehung und Haltung<\/span><\/h2>\n<h3 id=\"passt-ein-lwchen-zu-mir\">Passt ein L&ouml;wchen zu mir?<\/h3>\n<p><span style=\"font-weight: 400;\">Das L&ouml;wchen kann sehr gut in der <strong>Stadt<\/strong> und in einer <strong>Wohnung<\/strong>, auch selbst in einer kleinen Etagenwohnung im h&ouml;heren Stockwerk, gehalten werden. Nat&uuml;rlich braucht es t&auml;gliche <strong>Runden in der Natur<\/strong>, um sich wohlzuf&uuml;hlen und sein ausgeglichenes, freundliches Wesen voll entfalten zu k&ouml;nnen. Ansonsten ist er kleine Hund sehr anspruchslos, wenn er seine Bezugspersonen hat und dazu ein wenig <strong>abwechslungsreiche Besch&auml;ftigung<\/strong>. Lediglich sein Fell bedarf regelm&auml;&szlig;iger Pflege, damit es nicht verknotet. Diese kann man gut nutzen, um die Bindung zwischen ihm und Herrchen oder Frauchen zu festigen. Es sollte schon als Welpe an die <strong>regelm&auml;&szlig;ige Fellpflege<\/strong> gew&ouml;hnt werden. Das L&ouml;wchen ist ein wirklich idealer <strong>Familienhund<\/strong>, der sehr gut in einer Etagenwohnung gehalten werden kann. Es vertr&auml;gt sich bestens mit Kindern und ist ein guter Spielpartner, was aber wie immer voraussetzt, dass die Kinder ihn nicht als Spielzeug behandeln. Das L&ouml;wchen ist ein hervorragender Begleiter, der auch mit dem teils hektischen Gro&szlig;stadtleben zurecht kommt. Es kann in einer Gro&szlig;stadt problemlos gehalten werden, ob beim Single oder in einer Familie, ob jung oder alt. Das L&ouml;wchen ist agil und hellwach aber<strong> kein Kleffer<\/strong>. <\/span><\/p>\n<h3 id=\"kann-ich-ein-lwchen-erziehen\">Kann ich ein L&ouml;wchen erziehen?<\/h3>\n<p><span style=\"font-weight: 400;\">Der kleine Hund l&auml;sst sich sehr<strong> gut erziehen<\/strong>. Aber auch er muss erzogen werden. Sein putziges, drolliges, freundliches Wesen l&auml;sst allzu schnell &uuml;bersehen, dass er eine konsequente F&uuml;hrung und Erziehung braucht. Und er nimmt diese Verantwortung durch Herrchen und Frauchen gerne an. Seine hervorragende Eignung als Begleiter sollte nicht leichtfertig damit verwechselt werden, dass das L&ouml;wchen weniger Erziehung br&auml;uchte. Ganz im Gegenteil, seine hohe <strong>Intelligenz und Gelehrigkeit<\/strong> fordern geradezu die konsequente F&uuml;hrung durch seine Menschen, die &#8211; wie bei anderen Hunden auch &#8211; schon als Welpe beginnen sollte. Das f&auml;llt uns bei ihm zuweilen schwer, aber nicht, weil er nicht lernen k&ouml;nnte oder wollte. Vielmehr lassen wir Menschen uns gerne von diesem kleinen Gesellen als &#8222;putziges Wollkn&auml;uel&#8220; verzaubern und verh&auml;tscheln ihn dann.<\/span><\/p>\n<h2 id=\"interessantes-wissenswertes-extras\"><span style=\"font-weight: 400;\">Interessantes, Wissenswertes &amp; Extras<\/span><\/h2>\n<p><span style=\"font-weight: 400;\">Das hellwache und freundliche Wesen eines L&ouml;wchen erfreut unsere Herzen. Der schlaue, kleine Hund ist ein idealer Begleiter auch f&uuml;r eine Etagenwohnung in der Gro&szlig;stadt.<\/span><\/p>\n<hr>\n<p><a href=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/christoph-jung-140x168.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-5876 size-full alignleft\" src=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2017\/04\/christoph-jung-140x168.jpg\" alt=\"Christoph Jung\" width=\"140\" height=\"168\"><\/a><a href=\"\/magazin\/zoo-experten\/gastautoren-experten\/christoph-jung\/\"><strong>Christoph Jung<\/strong><\/a> Seit seiner Kindheit geh&ouml;ren Hunde zu den besten Freunden des Hundeforschers. Die Beziehung Mensch &#8211; Hund ist f&uuml;r ihn ein faszinierendes Thema, das ihn t&auml;glich besch&auml;ftigt und f&uuml;r das er sich auch &ouml;ffentlich engagiert. Aus seiner t&auml;glichen Forschung entstand das Buch <em>&#8222;Tierisch beste Freunde&#8220;<\/em>. Jung lebt mit seiner Familie und seinen Hunden in der N&auml;he von Halle.<\/p>\n<hr>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div id=\"pg-12585-1\" class=\"panel-grid panel-no-style\">\n<div id=\"pgc-12585-1-0\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-12585-1-0-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"1\"><\/div>\n<\/div>\n<div id=\"pgc-12585-1-1\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-12585-1-1-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"2\"><\/div>\n<\/div>\n<div id=\"pgc-12585-1-2\" class=\"panel-grid-cell\" data-weight=\"0.33333333333333\">\n<div id=\"panel-12585-1-2-0\" class=\"so-panel widget widget_rdss_zr_product_teaser panel-first-child panel-last-child\" data-index=\"3\"><\/div>\n<\/div>\n<\/div>\n<div id=\"pg-12585-2\" class=\"panel-grid panel-no-style\">\n<div id=\"pg-12585-2-0\" class=\"panel-grid-cell\" data-weight=\"1\">\n<div id=\"pg-12585-2-0-0\" class=\"so-panel widget widget_new_reco panel-first-child panel-last-child\" data-index=\"1\"><div\n\t\t\t\n\t\t\tclass=\"so-widget-new_reco so-widget-new_reco-default-d75171398898\"\n\t\t\t\n\t\t><aside class=\"products-desktop\" aria-label=\"Produktempfehlungen\">\n\n\n<span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n\n<div class=\"sc-zr-listing-container \">\n    <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-melaminnapf-grau-700ml\/1000074464\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melaminnapf grau 700ml\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/ph7f7i-zimOB6YE.jpg?host=ct\"\n                alt=\"ZooRoyal Melaminnapf grau 700ml\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melaminnapf grau 700ml<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    12.99 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-melaminnapf-grau-700ml\/1000074464\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/edgard-cooper-junior-ente-huhn-6x400g\/1000079514\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"Edgard und Cooper Junior Ente und Huhn 6x400g\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/oru7c7-uC4i4lpP.jpg?host=ct\"\n                alt=\"Edgard und Cooper Junior Ente und Huhn 6x400g\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    Edgard &amp; Cooper                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">Edgard und Cooper Junior Ente und Huhn 6x400g<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    18.99 EUR                <\/p>\n                                    <p class=\"zr-price__price-per-unit sc-zr-price\">\n                        7.91 \u20ac \/ 1 kg                    <\/p>\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/edgard-cooper-junior-ente-huhn-6x400g\/1000079514\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n        <article class=\"zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n        <a href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-wurfball-am-seil-gruen\/1000064375\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Wurfball am Seil gr\u00fcn\" target=\"_blank\">\n\n\n        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n            <img decoding=\"async\"\n                src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/2vedjh-jabh_6WM.jpg?host=ct\"\n                alt=\"ZooRoyal Wurfball am Seil gr\u00fcn\">\n\n        <\/div>\n        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                    ZooRoyal                <\/div>\n                <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Wurfball am Seil gr\u00fcn<\/p>\n        <\/div>\n        <\/a>\n\n\n        <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n            <div class=\"zr-price__wrapper sc-zr-price\">\n                <p class=\"zr-price__current-price p-price sc-zr-price\">\n                    4.49 EUR                <\/p>\n                                    <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                            <\/div>\n            <div class=\"text-center btn-wrapper\">\n                <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-wurfball-am-seil-gruen\/1000064375\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                    Zum Produkt\n                <\/a>\n            <\/div>\n        <\/div>\n\n\n    <\/article>\n\n    <\/div>\n<\/aside>\n\n\n<!-- End Products-Desktop -->\n<aside class=\"products-mobile\" aria-label=\"Produktempfehlungen\">\n\n    <span class=\"product-teaser-headline\">Unsere Lieblingsprodukte f\u00fcr dich<\/span>\n    <div class=\"sc-zr-listing-container \">\n\n\n    <!-- Start Products-Mobile -->\n    <div class=\"swiper mySwiper6a04906baa3e3\">\n        <div class=\"swiper-wrapper\">\n\n                        <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-melaminnapf-grau-700ml\/1000074464\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Melaminnapf grau 700ml\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/ph7f7i-zimOB6YE.jpg?host=ct\"\n                                    alt=\"ZooRoyal Melaminnapf grau 700ml\">\n\n                            <div id=\"swiper-button-next6a04906baa3e3\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04906baa3e3\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Melaminnapf grau 700ml<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                12.99 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-melaminnapf-grau-700ml\/1000074464\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/edgard-cooper-junior-ente-huhn-6x400g\/1000079514\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"Edgard und Cooper Junior Ente und Huhn 6x400g\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/oru7c7-uC4i4lpP.jpg?host=ct\"\n                                    alt=\"Edgard und Cooper Junior Ente und Huhn 6x400g\">\n\n                            <div id=\"swiper-button-next6a04906baa3e3\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04906baa3e3\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                Edgard &amp; Cooper                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">Edgard und Cooper Junior Ente und Huhn 6x400g<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                18.99 EUR                            <\/p>\n                                                            <p class=\"zr-price__price-per-unit sc-zr-price\">\n                                    7.91 \u20ac \/ 1 kg                                <\/p>\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/edgard-cooper-junior-ente-huhn-6x400g\/1000079514\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                            <div class=\"swiper-slide\">\n                <article class=\"swiper-content zr-product-tile zr-product-tile__sponsored sc-zr-product-tile\">\n                    <a href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-wurfball-am-seil-gruen\/1000064375\/?icid=magproteaser_hunde_hunderassen_loewchen_\" class=\"article__wrapper--productimage\" title=\"ZooRoyal Wurfball am Seil gr\u00fcn\" target=\"_blank\">\n\n\n                        <div class=\"zr-product-tile__image sc-zr-product-tile\">\n                            <img decoding=\"async\"\n                                    src=\"https:\/\/www.zooroyal.de\/api\/image\/48f20ab7-8172-4f6f-915e-02c589fad1d5\/2vedjh-jabh_6WM.jpg?host=ct\"\n                                    alt=\"ZooRoyal Wurfball am Seil gr\u00fcn\">\n\n                            <div id=\"swiper-button-next6a04906baa3e3\" class=\"swiper-button-next\"><\/div>\n                            <div id=\"swiper-button-prev6a04906baa3e3\" class=\"swiper-button-prev\"><\/div>\n\n                        <\/div>\n                        <div class=\"zr-product-tile__detail sc-zr-product-tile\">\n                            <div class=\"zr-product-tile__supplier sc-zr-product-tile\">\n                                ZooRoyal                            <\/div>\n                            <p class=\"zr-product-tile__name sc-zr-product-tile\">ZooRoyal Wurfball am Seil gr\u00fcn<\/p>\n                        <\/div>\n                    <\/a>\n\n\n                    <div class=\"zr-price--listing sc-zr-product-tile hydrated\">\n                        <div class=\"zr-price__wrapper sc-zr-price\">\n                            <p class=\"zr-price__current-price p-price sc-zr-price\">\n                                4.49 EUR                            <\/p>\n                                                            <div class=\"zr-price__placeholder\"><\/div> <!-- Optional: Platzhalter -->\n                                                    <\/div>\n                        <div class=\"text-center btn-wrapper\">\n                            <a class=\"btn rounded\" href=\"https:\/\/www.zooroyal.de\/p\/zooroyal-wurfball-am-seil-gruen\/1000064375\/?icid=magproteaser_hunde_hunderassen_loewchen_\" target=\"_blank\">\n                                Zum Produkt\n                            <\/a>\n                        <\/div>\n\n\n                    <\/div>\n\n\n                <\/article>\n\n\n            <\/div>\n\n\n\n                        <\/div>\n\n        <div class=\"swiper-pagination-container\">\n        <div class=\"swiper-pagination\"><\/div>\n        <\/div>\n\n    <\/div>\n\n    <!-- Initialize Swiper -->\n    <script>\n        var swiper = new Swiper(\".mySwiper6a04906baa3e3\", {\n            loop: false,\n\n            navigation: {\n                nextEl: \"#swiper-button-next6a04906baa3e3\",\n                prevEl: \"#swiper-button-prev6a04906baa3e3\",\n            },\n            slidesPerView: 1.0,\n            centeredSlides: true,\n            spaceBetween: 10,\n            autoHeight: false,\n            effect: 'coverflow',\n            coverflowEffect: {\n                rotate: 30,\n                slideShadows: true,\n            },\n            keyboard: {\n                enabled: true,\n                onlyInViewport: false,\n            },\n            pagination: {\n                el: '.swiper-pagination',\n                clickable: true,\n            },\n        });\n    <\/script>\n<\/div>\n<\/aside>\n<\/div>\n                    <\/div>\n<\/p><\/div>\n<\/p><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rassenmerkmale und Erscheinungsbild Wie sieht ein L&ouml;wchen aus? Das L&ouml;wchen, im Original &#8222;Petit Chien Lion&#8220;, ist eher kleiner Hund mit langem, seidigem Fell. Das L&ouml;wchen hat ein quadratisches Geb&auml;ude, das&#8230; <a class=\"moretag\" href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hunderassen\/loewchen\/\">weiterlesen<\/a><\/p>\n","protected":false},"author":35,"featured_media":12589,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2040,2048,5,903,2035,2036],"tags":[1701,808,2079,2080],"class_list":["post-12585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-familienhunde","category-fci-gruppe-9","category-hunde","category-hunderassen","category-kleine-hunderassen","category-mini-hunderassen","tag-bichon","tag-kleine-hunderassen","tag-loewchen","tag-petit-chien-lion"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>L\u00f6wchen - Charakter, Gr\u00f6\u00dfe &amp; Erziehung | Steckbrief<\/title>\n<meta name=\"description\" content=\"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L\u00f6wchen\" \/>\n<meta property=\"og:description\" content=\"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ZooRoyalDE\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-18T13:09:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-03T12:42:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"760\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ZooRoyal\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"ZooRoyal\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/\"},\"author\":{\"name\":\"ZooRoyal\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\"},\"headline\":\"L\u00f6wchen\",\"datePublished\":\"2018-04-18T13:09:49+00:00\",\"dateModified\":\"2024-07-03T12:42:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/\"},\"wordCount\":1889,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/loewchen-760x560.jpg\",\"keywords\":[\"Bichon\",\"Kleine Hunderassen\",\"L\u00f6wchen\",\"Petit Chien Lion\"],\"articleSection\":[\"Familienhunde\",\"FCI Gruppe 9\",\"Hunde Magazin\",\"Hunderassen\",\"Kleine Hunderassen\",\"Mini Hunderassen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/\",\"name\":\"L\u00f6wchen - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/loewchen-760x560.jpg\",\"datePublished\":\"2018-04-18T13:09:49+00:00\",\"dateModified\":\"2024-07-03T12:42:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\"},\"description\":\"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/loewchen-760x560.jpg\",\"contentUrl\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/loewchen-760x560.jpg\",\"width\":760,\"height\":560,\"caption\":\"L\u00f6wchen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/loewchen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L\u00f6wchen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#\\\/schema\\\/person\\\/2d4f21e50479b72c19f7f67436e3dcf2\",\"name\":\"ZooRoyal\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"url\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/zooroyal.de\\\/magazin\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/avatar_user_35_1558596332-96x96.jpg\",\"caption\":\"ZooRoyal\"},\"sameAs\":[\"https:\\\/\\\/www.zooroyal.de\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L\u00f6wchen - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief","description":"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/","og_locale":"de_DE","og_type":"article","og_title":"L\u00f6wchen","og_description":"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/","og_site_name":"ZooRoyal Magazin","article_publisher":"https:\/\/www.facebook.com\/ZooRoyalDE","article_published_time":"2018-04-18T13:09:49+00:00","article_modified_time":"2024-07-03T12:42:34+00:00","og_image":[{"width":760,"height":560,"url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg","type":"image\/jpeg"}],"author":"ZooRoyal","twitter_card":"summary_large_image","twitter_creator":"@zooroyal","twitter_site":"@zooroyal","twitter_misc":{"Written by":"ZooRoyal","Est. reading time":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#article","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/"},"author":{"name":"ZooRoyal","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2"},"headline":"L\u00f6wchen","datePublished":"2018-04-18T13:09:49+00:00","dateModified":"2024-07-03T12:42:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/"},"wordCount":1889,"commentCount":0,"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg","keywords":["Bichon","Kleine Hunderassen","L\u00f6wchen","Petit Chien Lion"],"articleSection":["Familienhunde","FCI Gruppe 9","Hunde Magazin","Hunderassen","Kleine Hunderassen","Mini Hunderassen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/","name":"L\u00f6wchen - Charakter, Gr\u00f6\u00dfe & Erziehung | Steckbrief","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#primaryimage"},"image":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg","datePublished":"2018-04-18T13:09:49+00:00","dateModified":"2024-07-03T12:42:34+00:00","author":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2"},"description":"Das L\u00f6wchen geh\u00f6rt zu den Bichons und ist einer der \u00e4ltesten Begleithunde der Welt. Lies hier alles \u00fcber den freundlichen Gesellschaftshund.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#primaryimage","url":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg","contentUrl":"https:\/\/www.zooroyal.de\/magazin\/wp-content\/uploads\/2018\/03\/loewchen-760x560.jpg","width":760,"height":560,"caption":"L\u00f6wchen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/loewchen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"L\u00f6wchen"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.zooroyal.de\/magazin\/#\/schema\/person\/2d4f21e50479b72c19f7f67436e3dcf2","name":"ZooRoyal","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","url":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","contentUrl":"https:\/\/zooroyal.de\/magazin\/wp-content\/uploads\/2019\/05\/avatar_user_35_1558596332-96x96.jpg","caption":"ZooRoyal"},"sameAs":["https:\/\/www.zooroyal.de"]}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/12585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/comments?post=12585"}],"version-history":[{"count":21,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/12585\/revisions"}],"predecessor-version":[{"id":33330,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts\/12585\/revisions\/33330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/media\/12589"}],"wp:attachment":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/media?parent=12585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/categories?post=12585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/tags?post=12585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}