{"id":3951,"count":15,"description":"","link":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/","name":"Hundetricks f\u00fcr Fortgeschrittene","slug":"hundetricks-fuer-fortgeschrittene","taxonomy":"category","parent":3886,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.6 (Yoast SEO v27.5) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hundetricks f\u00fcr Fortgeschrittene | ZooRoyal Magazin<\/title>\n<meta name=\"description\" content=\"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hundetricks f\u00fcr Fortgeschrittene Archive\" \/>\n<meta property=\"og:description\" content=\"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/\" \/>\n<meta property=\"og:site_name\" content=\"ZooRoyal Magazin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@zooroyal\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hundetricks\\\/hundetricks-fuer-fortgeschrittene\\\/\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hundetricks\\\/hundetricks-fuer-fortgeschrittene\\\/\",\"name\":\"Hundetricks f\u00fcr Fortgeschrittene | ZooRoyal Magazin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\"},\"description\":\"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hundetricks\\\/hundetricks-fuer-fortgeschrittene\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hundetricks\\\/hundetricks-fuer-fortgeschrittene\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hunde Magazin\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Hundetricks\",\"item\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/hunde\\\/hundetricks\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Hundetricks f\u00fcr Fortgeschrittene\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/#website\",\"url\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/\",\"name\":\"ZooRoyal Magazin\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.zooroyal.de\\\/magazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hundetricks f\u00fcr Fortgeschrittene | ZooRoyal Magazin","description":"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/","og_locale":"de_DE","og_type":"article","og_title":"Hundetricks f\u00fcr Fortgeschrittene Archive","og_description":"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.","og_url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/","og_site_name":"ZooRoyal Magazin","twitter_card":"summary_large_image","twitter_site":"@zooroyal","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/","url":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/","name":"Hundetricks f\u00fcr Fortgeschrittene | ZooRoyal Magazin","isPartOf":{"@id":"https:\/\/www.zooroyal.de\/magazin\/#website"},"description":"Hier zeigen wir dir Step-by-Step Hundetricks f\u00fcr Fortgeschrittene. Bringe deinem Hund damit ganz easy R\u00fcckw\u00e4rts gehen oder Socken ausziehen bei.","breadcrumb":{"@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/hundetricks-fuer-fortgeschrittene\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.zooroyal.de\/magazin\/"},{"@type":"ListItem","position":2,"name":"Hunde Magazin","item":"https:\/\/www.zooroyal.de\/magazin\/hunde\/"},{"@type":"ListItem","position":3,"name":"Hundetricks","item":"https:\/\/www.zooroyal.de\/magazin\/hunde\/hundetricks\/"},{"@type":"ListItem","position":4,"name":"Hundetricks f\u00fcr Fortgeschrittene"}]},{"@type":"WebSite","@id":"https:\/\/www.zooroyal.de\/magazin\/#website","url":"https:\/\/www.zooroyal.de\/magazin\/","name":"ZooRoyal Magazin","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zooroyal.de\/magazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/categories\/3951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/categories\/3886"}],"wp:post_type":[{"href":"https:\/\/www.zooroyal.de\/magazin\/wp-json\/wp\/v2\/posts?categories=3951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}